{"id":10247,"date":"2018-06-25T00:00:00","date_gmt":"2018-06-25T00:00:00","guid":{"rendered":"https:\/\/www.mercator-ocean.eu\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/"},"modified":"2018-06-25T00:00:00","modified_gmt":"2018-06-25T00:00:00","slug":"monde-fr-climat-systeme-terre-levolution-modeles-globaux","status":"publish","type":"post","link":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/","title":{"rendered":"Le monde.fr &#8211; Du climat au Syst\u00e8me Terre : l\u2019\u00e9volution des mod\u00e8les globaux"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div><h3>Estimer l\u2019impact des changements climatiques sur les soci\u00e9t\u00e9s humaines implique de parfaire la connaissance des processus en jeu. La complexit\u00e9 du climat terrestre oblige aujourd\u2019hui \u00e0 adopter des approches int\u00e9gr\u00e9es m\u00ealant physique, biologie et socio-\u00e9conomie.<\/h3>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/oceanclimat.blog.lemonde.fr\/files\/2018\/05\/599px-The_Earth_seen_from_Apollo_17-300x300.jpg\" \/><\/p>\n<p>Le climat terrestre, et son couplage avec les dynamiques atmosph\u00e9riques et oc\u00e9aniques, est un objet complexe dont l\u2019analyse et la pr\u00e9vision ne saurait se faire autrement que par le recours \u00e0 de lourds mod\u00e8les num\u00e9riques, les capacit\u00e9s de calculs des ordinateurs modernes autorisant \u00e0 traiter les nombreux jeux de donn\u00e9es requis. Contrairement \u00e0 une id\u00e9e re\u00e7ue v\u00e9hicul\u00e9e par les d\u00e9tracteurs des travaux du GIEC (Groupe d\u2019experts Intergouvernemental sur l\u2019Evolution du Climat, dont le mandat est l\u2019\u00e9tude des changements climatiques) les mod\u00e8les climatiques ne sont pas tautologiques (c\u2019est-\u00e0-dire biais\u00e9s d\u00e8s leur conception pour ne montrer que des r\u00e9sultats d\u00e9j\u00e0 attendus, bas\u00e9s sur des donn\u00e9es empiriques orient\u00e9es, et donc sans rigueur scientifique). Au contraire, les mod\u00e8les sont la traduction math\u00e9matique des m\u00e9canismes th\u00e9oris\u00e9s sur la base des observations.\u00a0Si les donn\u00e9es de terrain ont \u00e9videmment leur r\u00f4le \u00e0 jouer (sans cela ils seraient d\u00e9connect\u00e9s des r\u00e9alit\u00e9s, nous en reparlerons), c\u2019est bien la reformulation math\u00e9matique des ph\u00e9nom\u00e8nes en jeu qui en est la base.<\/p>\n<h4>De la simulation physique aux mod\u00e8les du Syst\u00e8me Terre<\/h4>\n<p>Les bases physiques du climat terrestre sont aujourd\u2019hui solidement \u00e9tablies (bien qu\u2019\u00e9videmment perfectibles) et les mod\u00e8les correspondants relativement robustes. Ces acquis ne sont cependant pas suffisants pour simuler pr\u00e9cis\u00e9ment les trajectoires possibles du climat \u00e0 venir. Plus difficilement accessible et mesurable, la contribution de la biosph\u00e8re, du monde vivant, aux variations du climat a longtemps \u00e9t\u00e9 absente des mod\u00e8les. Dans un article paru dans\u00a0<em>Science\u00a0<\/em>en f\u00e9vrier 2018 Gordon B. Bonan et Scott C. Doney  d\u00e9crivent ainsi la n\u00e9cessit\u00e9 de passer des bases physiques du climat \u00e0 des mod\u00e8les plus complexes du Syst\u00e8me Terre (Earth System Models ou ESMs) qui int\u00e8grent variables physico-chimiques, variables \u00e9cologiques et variables socio-\u00e9conomiques au sein d\u2019un cadre commun.<\/p>\n<p>Le lien entre monde vivant et climat est tr\u00e8s souvent pr\u00e9sent\u00e9 au prisme de la vuln\u00e9rabilit\u00e9\u00a0: les organismes \u00ab\u00a0subissant\u00a0\u00bb les variations du climat qui sont autant de facteurs de stress. Moins connue en revanche est la capacit\u00e9 des \u00eatres vivants \u00e0 modifier leur environnement. Cette capacit\u00e9 ne se limite pas aux organismes ing\u00e9nieurs (\u00e0 l\u2019image des coraux ou des castors dont l\u2019action environnementale est \u00e9vidente) et tous contribuent \u00e0 modifier les conditions de leur habitat (\u00e0 des degr\u00e9s et amplitudes vari\u00e9s).<\/p>\n<p>C\u2019est pourquoi cette int\u00e9gration est si importante\u00a0: un cadre commun permet certes d\u2019identifier et de quantifier le degr\u00e9 de vuln\u00e9rabilit\u00e9 de chaque esp\u00e8ce, mais il permet aussi d\u2019estimer l\u2019impact de chacune sur le climat (ces r\u00e9troactions prenant la forme d\u2019\u00e9changes de masses et d\u2019\u00e9nergies entre biosph\u00e8re, hydrosph\u00e8re et atmosph\u00e8re). En outre, les mod\u00e8les de Syst\u00e8me Terre permettent d\u2019exprimer les cons\u00e9quences des changements climatiques avec des indicateurs plus pertinents pour les soci\u00e9t\u00e9s humaines (l\u00e0 o\u00f9 une simulation purement physique fournira des pr\u00e9visions en termes de temp\u00e9ratures, de cycles hydrologiques, les mod\u00e8les du Syst\u00e8me Terre donneront acc\u00e8s aux cons\u00e9quences des changements sur le rendement des cultures, des p\u00eacheries\u2026).<\/p>\n<p>L\u2019int\u00e9gration de la sph\u00e8re socio-\u00e9conomique \u00e0 la mod\u00e9lisation climatique a elle aussi son importance \u00e9tant donn\u00e9 le r\u00f4le d\u00e9terminant des activit\u00e9s humaines sur le climat. Elle permet d\u2019exprimer diff\u00e9rents sc\u00e9narios de d\u00e9veloppement, durable ou non, en termes d\u2019\u00e9missions et d\u2019acc\u00e9der aux valeurs de r\u00e9chauffements correspondantes\u00a0; tout comme elle permet d\u2019estimer les impacts probables des changements sur les soci\u00e9t\u00e9s. L\u2019approche ESMs permet ainsi de combiner les bases physiques des changements climatiques, d\u2019estimer les possibilit\u00e9s d\u2019att\u00e9nuation et d\u2019\u00e9valuer la vuln\u00e9rabilit\u00e9, l\u2019impact, et les trajectoires d\u2019adaptation.<\/p>\n<h4>Trois foyers d\u2019incertitude, et autant d\u2019appels \u00e0 l\u2019action<\/h4>\n<p>Dans l\u2019\u00e9tat actuel des connaissances, l\u2019int\u00e9gration du vivant dans le cadre de mod\u00e8les syst\u00e9miques diminue la pr\u00e9cision des pr\u00e9visions, la r\u00e9solution spatiale, et augmente les incertitudes. Lors des Rendez-vous Oc\u00e9an et Climat  organis\u00e9s par la Plateforme Oc\u00e9an et Climat (POC) en mars dernier, Fabrice Messal (Mercator Oc\u00e9an, Conseil Scientifique de la POC) disait \u00e0 ce propos\u00a0: \u00ab\u00a0Les mod\u00e8les actuels  ont une r\u00e9solution de 300 millions de points soit un douzi\u00e8me de degr\u00e9. L\u2019ajout des variables biog\u00e9ochimiques diminue cette r\u00e9solution\u00a0: les \u00eatres vivants sont trop complexes pour les mod\u00e8les d\u2019aujourd\u2019hui.\u00a0\u00bb Dans leur article Bonan et Doney distinguent trois foyers d\u2019incertitudes, qui sont autant de pistes pour orienter la recherche future.<\/p>\n<p>Un premier foyer d\u2019incertitude r\u00e9side dans l\u2019initialisation du mod\u00e8le. Pour ce faire, on le param\u00e8tre avec diff\u00e9rentes conditions initiales qui correspondent en pratique \u00e0 des jeux de donn\u00e9es issues d\u2019observations. Pour r\u00e9duire l\u2019incertitude, il est d\u2019usage de faire tourner le mod\u00e8le avec diff\u00e9rents jeux de donn\u00e9es initiales\u00a0: \u00e0 ce titre plus le nombre de donn\u00e9es disponibles est important, plus l\u2019incertitude se r\u00e9duit.<\/p>\n<p>Il est donc crucial d\u2019encourager et de poursuivre les efforts de recherche que ce soit en physique, en biologie mais aussi dans les sciences humaines et sociales. Derni\u00e8rement, les travaux de Casimir de Lavergne et de son \u00e9quipe publi\u00e9s dans\u00a0<em>Nature \u00a0<\/em>en septembre 2017 ont pr\u00e9cis\u00e9 la connaissance de la circulation oc\u00e9anique et mis en \u00e9vidence leur d\u00e9pendance \u00e0 la topographie des fonds marins (l\u2019\u00e9tude a en effet montr\u00e9 que la structure de la circulation est contrainte par le relief du fond des grands bassins \u00e9tudi\u00e9s \u2013 Pacifique, Indien et Atlantique).<\/p>\n<p>Toujours dans\u00a0<em>Nature<\/em>, Perez et al.\u00a0<em>\u00a0<\/em>ont montr\u00e9 en f\u00e9vrier 2018 comment la circulation oc\u00e9anique entrainait l\u2019acidification des profondeurs de l\u2019oc\u00e9an Atlantique \u00e0 un rythme bien sup\u00e9rieur aux estimations pr\u00e9c\u00e9dentes. L\u2019horizon de saturation d\u2019aragonite (en dessous duquel la dissolution est favoris\u00e9e) pourrait ainsi plonger de 1000 \u00e0 1700m d\u2019ici 30 ans et ainsi menacer les coraux profonds. Katherine Kornei a expos\u00e9 dans\u00a0<em>Science\u00a0<\/em>en 2018\u00a0<em>\u00a0<\/em>les r\u00e9sultats in\u00e9dits d\u2019une campagne d\u2019observation qui r\u00e9v\u00e8le une branche de la circulation atlantique jusqu\u2019ici largement sous-estim\u00e9e \u00e0 l\u2019Est du Groenland, l\u00e0 o\u00f9 les efforts d\u2019observation traduits ensuite dans les mod\u00e8les se concentraient sur la Mer du Labrador \u00e0 l\u2019Ouest du Groenland (r\u00e9sultat surprenant dans le contexte actuel d\u2019affaiblissement de cette circulation). Tous ces r\u00e9sultats viennent compl\u00e9ter les connaissances physiques des mod\u00e8les oc\u00e9aniques, il est aujourd\u2019hui urgent d\u2019en faire de m\u00eame avec le vivant.<\/p>\n<p>Une autre source d\u2019incertitude est intrins\u00e8que au mod\u00e8le et correspond aux erreurs de repr\u00e9sentation des processus en jeu. Les \u00ab\u00a0erreurs de mod\u00e8les\u00a0\u00bb (dues \u00e0 une transcription math\u00e9matique et num\u00e9rique incompl\u00e8te des ph\u00e9nom\u00e8nes \u00e9tudi\u00e9s) peuvent aussi provenir d\u2019erreurs d\u2019estimations, d\u2019approximations dans le poids accord\u00e9 aux diff\u00e9rents ph\u00e9nom\u00e8nes. Pour y pallier ou au moins en estimer l\u2019amplitude, il est d\u2019usage de faire tourner plusieurs mod\u00e8les avec le m\u00eame jeu de donn\u00e9es initiales et les m\u00eames contraintes.<\/p>\n<p>La r\u00e9solution des incertitudes inh\u00e9rentes au mod\u00e8le implique de mieux connaitre les processus impliqu\u00e9s. Sur ce point, deux articles publi\u00e9s en janvier 2018 dans\u00a0<em>Nature<a name=\"_ftnref\"><\/a>\u00a0\u00a0<\/em>par Piers Forster, et par Peter M. Cox et son \u00e9quipe apportent des pr\u00e9cisions d\u2019une importance cruciale en pr\u00e9cisant la sensibilit\u00e9 du climat aux concentrations de CO<sub>2<\/sub>. Cette donn\u00e9e est d\u2019une extr\u00eame importance car elle quantifie la valeur de r\u00e9chauffement associ\u00e9e \u00e0 un doublement de la concentration en CO<sub>2\u00a0<\/sub>atmosph\u00e9rique (dans son rapport de 2013 le GIEC estimait qu\u2019un doublement du CO<sub>2\u00a0<\/sub>atmosph\u00e9rique se traduirait par un r\u00e9chauffement de 1,5 \u00e0 4,5\u00b0C\u00a0; dans les travaux les plus r\u00e9cents men\u00e9s par Cox et al. cette valeur est pr\u00e9cis\u00e9e \u00e0 2,2-3,4\u00b0C).<\/p>\n<p>Sur un autre registre Tim DeVries a publi\u00e9 dans\u00a0<em>Nature<a name=\"_ftnref\"><\/a>\u00a0<\/em>en f\u00e9vrier 2017 de nouvelles estimations du devenir de la \u00ab\u00a0pompe \u00e0 carbone oc\u00e9anique\u00a0\u00bb (laquelle d\u00e9pend de nombreux processus dont les r\u00e9ponses aux changements climatiques sont parfois antagonistes)\u00a0: l\u2019affaiblissement de la circulation de retournement pourrait selon ses r\u00e9sultats accro\u00eetre l\u2019absorption nette de carbone en diminuant les rejets dans les zones de remont\u00e9e des eaux tropicales. Dans la continuit\u00e9 de ces travaux, le besoin de mieux comprendre les ph\u00e9nom\u00e8nes en jeu (tant physiques qu\u2019ayant trait \u00e0 la biologie ou aux cycles biog\u00e9ochimiques) doit \u00eatre pris en compte dans la d\u00e9finition des politiques de recherche.<\/p>\n<p>Finalement les incertitudes proviennent aussi des biais de sc\u00e9narisation. Pour passer bri\u00e8vement sur ce dernier point, on notera seulement que nul ne peut se targuer de connaitre les trajectoires des d\u00e9veloppements socio-\u00e9conomiques (et des \u00e9missions de CO<sub>2<\/sub>associ\u00e9es) \u00e0 venir. Les sc\u00e9narios ne sont que la poursuite de tendances actuelles affect\u00e9es de diff\u00e9rents postulats. Cependant, une meilleure connaissance des conditions politiques et socio-\u00e9conomiques ne peut que profiter \u00e0 ce difficile exercice.<\/p>\n<h4>Quel message tirer de ces progr\u00e8s de la mod\u00e9lisation\u00a0?<\/h4>\n<p>On retiendra l\u2019importance de disposer de jeux de donn\u00e9es \u00e9toff\u00e9es, de comprendre et repr\u00e9senter les m\u00e9canismes physiques, biog\u00e9ochimiques et biologiques impliqu\u00e9s dans le fonctionnement et la variabilit\u00e9 du climat et de pouvoir tester les mod\u00e8les sur des conditions connues du climat pass\u00e9 rendues accessibles par la pal\u00e9oclimatologie. \u00a0A ce titre il est crucial de continuer \u00e0 investir dans la recherche.<\/p>\n<p>La connaissance scientifique est indispensable \u00e0 toute politique cr\u00e9dible d\u2019adaptation et d\u2019att\u00e9nuation des changements climatiques. Elle en constitue les conditions pr\u00e9alables et les fondements.<\/p>\n<p><strong>Le monde vivant a un statut particulier\u00a0:\u00a0<\/strong>source de solutions, il est au c\u0153ur des sc\u00e9narios d\u2019att\u00e9nuation\/adaptation.Les connaissances des \u00e9cosyst\u00e8mes oc\u00e9aniques sont encore lacunaires compar\u00e9 \u00e0 leurs \u00e9quivalent terrestre (du fait entre autres de la difficult\u00e9 d\u2019acc\u00e8s \u00e0 des environnements comme l\u2019oc\u00e9an profond), pourtant n\u00e9cessaires pour mieux comprendre les processus et les r\u00e9troactions biologiques sur le climat.<\/p>\n<p>Au rythme actuel d\u2019\u00e9rosion de la biodiversit\u00e9 (dont l\u2019acc\u00e9l\u00e9ration est \u00e0 craindre) nos options se r\u00e9duisent. Il est urgent d\u2019agir\u00a0et la connaissance doit \u00eatre au fondement des choix de gestion\/protection et des trajectoires de d\u00e9veloppement futures.<\/p>\n<p>Antoine PEBAYLE, Plateforme Oc\u00e9an et Climat<\/p>\n<p><a name=\"_ftn1\"><\/a><em>Climate, ecosystems, and planetary futures: The challenge to predict life in Earth system models<\/em>, G. B. Bonan &amp; S. C. Doney, Science vol. 359 (02\/02\/2018)<\/p>\n<p><a name=\"_ftn2\"><\/a>https:\/\/ocean-climate.org\/?p=5268<\/p>\n<p><a name=\"_ftn3\"><\/a><em>Abyssal ocean overturning shaped by seafloor distribution<\/em>, C. de Lavergne, C. Madec, F. Roquet, R.M. Holmes &amp; T. J. McDougall, Nature vol. 551 (09\/11\/2017)<\/p>\n<p><a name=\"_ftn4\"><\/a><em>Meridional overturning circulation conveys fast acidification to the deep Atlantic Ocean<\/em>, Perez et al., Nature vol. 554 (22\/02\/2018)<\/p>\n<p><a name=\"_ftn5\"><\/a><em>Ocean array alters view of Atlantic conveyor<\/em>, Katherine Kornei, Science vol. 359 (23\/02\/2018)<\/p>\n<p><a name=\"_ftn6\"><\/a><em>Homing in on a key factor of climate change<\/em>, Piers Forster, Nature vol. 553 (18\/01\/2018) ;\u00a0<em>Emergent constraint on equilibrium climate sensitivity from global temperature variability<\/em>, Peter M. Cox, Chris Huntingford &amp; Mark S. Williamson, Nature vol. 553 (18\/01\/2018)<\/p>\n<p><a name=\"_ftn7\"><\/a><em>Recent increase in oceanic carbon uptake driven by weaker upper-ocean overturning<\/em>, Tim DeVries, Mark Holzer &amp; Fran\u00e7ois Primeau, Nature vol. 542 (09\/02\/2017)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimer l\u2019impact des changements climatiques sur les soci\u00e9t\u00e9s humaines implique de parfaire la connaissance des processus en jeu. La complexit\u00e9 du climat terrestre oblige aujourd\u2019hui \u00e0 adopter des approches int\u00e9gr\u00e9es m\u00ealant physique, biologie et socio-\u00e9conomie. Le climat terrestre, et son couplage avec les dynamiques atmosph\u00e9riques et oc\u00e9aniques, est un objet complexe dont l\u2019analyse et la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[38],"tags":[],"translation-status":[],"class_list":["post-10247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-on-parle-de-nous"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le monde.fr - Du climat au Syst\u00e8me Terre : l\u2019\u00e9volution des mod\u00e8les globaux - Mercator Ocean International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le monde.fr - Du climat au Syst\u00e8me Terre : l\u2019\u00e9volution des mod\u00e8les globaux - Mercator Ocean International\" \/>\n<meta property=\"og:description\" content=\"Estimer l\u2019impact des changements climatiques sur les soci\u00e9t\u00e9s humaines implique de parfaire la connaissance des processus en jeu. La complexit\u00e9 du climat terrestre oblige aujourd\u2019hui \u00e0 adopter des approches int\u00e9gr\u00e9es m\u00ealant physique, biologie et socio-\u00e9conomie. Le climat terrestre, et son couplage avec les dynamiques atmosph\u00e9riques et oc\u00e9aniques, est un objet complexe dont l\u2019analyse et la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/\" \/>\n<meta property=\"og:site_name\" content=\"Mercator Ocean International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MercatorOcean\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-25T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mercator-ocean.eu\/wp-content\/uploads\/2024\/03\/logo-M-blogs-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"247\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Damien Goubeau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MercatorOcean\" \/>\n<meta name=\"twitter:site\" content=\"@MercatorOcean\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Goubeau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/\"},\"author\":{\"name\":\"Damien Goubeau\",\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/#\\\/schema\\\/person\\\/8707759d6e2641e91ea76ae3fc537134\"},\"headline\":\"Le monde.fr &#8211; Du climat au Syst\u00e8me Terre : l\u2019\u00e9volution des mod\u00e8les globaux\",\"datePublished\":\"2018-06-25T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/\"},\"wordCount\":1976,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-M-blogs-02.jpg\",\"articleSection\":[\"On parle de nous\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/\",\"url\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/\",\"name\":\"Le monde.fr - Du climat au Syst\u00e8me Terre : l\u2019\u00e9volution des mod\u00e8les globaux - Mercator Ocean International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-M-blogs-02.jpg\",\"datePublished\":\"2018-06-25T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-M-blogs-02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-M-blogs-02.jpg\",\"width\":700,\"height\":247},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/on-parle-de-nous\\\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le monde.fr &#8211; Du climat au Syst\u00e8me Terre : l\u2019\u00e9volution des mod\u00e8les globaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/\",\"name\":\"Mercator Ocean International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/#organization\",\"name\":\"Mercator Ocean International\",\"url\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/logo-mercator.png\",\"contentUrl\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/logo-mercator.png\",\"width\":541,\"height\":547,\"caption\":\"Mercator Ocean International\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MercatorOcean\",\"https:\\\/\\\/x.com\\\/MercatorOcean\",\"https:\\\/\\\/www.instagram.com\\\/mercator_ocean\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mercator-ocean\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/MERCATOROCEAN\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/#\\\/schema\\\/person\\\/8707759d6e2641e91ea76ae3fc537134\",\"name\":\"Damien Goubeau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62d2ec81cbbe6e9a2a721e1d515895cfdffad7498f8f55b118245bbb7dc6b982?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62d2ec81cbbe6e9a2a721e1d515895cfdffad7498f8f55b118245bbb7dc6b982?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62d2ec81cbbe6e9a2a721e1d515895cfdffad7498f8f55b118245bbb7dc6b982?s=96&d=mm&r=g\",\"caption\":\"Damien Goubeau\"},\"url\":\"https:\\\/\\\/www.mercator-ocean.eu\\\/fr\\\/author\\\/damien-goubeau\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le monde.fr - Du climat au Syst\u00e8me Terre : l\u2019\u00e9volution des mod\u00e8les globaux - Mercator Ocean International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Le monde.fr - Du climat au Syst\u00e8me Terre : l\u2019\u00e9volution des mod\u00e8les globaux - Mercator Ocean International","og_description":"Estimer l\u2019impact des changements climatiques sur les soci\u00e9t\u00e9s humaines implique de parfaire la connaissance des processus en jeu. La complexit\u00e9 du climat terrestre oblige aujourd\u2019hui \u00e0 adopter des approches int\u00e9gr\u00e9es m\u00ealant physique, biologie et socio-\u00e9conomie. Le climat terrestre, et son couplage avec les dynamiques atmosph\u00e9riques et oc\u00e9aniques, est un objet complexe dont l\u2019analyse et la [&hellip;]","og_url":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/","og_site_name":"Mercator Ocean International","article_publisher":"https:\/\/www.facebook.com\/MercatorOcean","article_published_time":"2018-06-25T00:00:00+00:00","og_image":[{"width":700,"height":247,"url":"https:\/\/www.mercator-ocean.eu\/wp-content\/uploads\/2024\/03\/logo-M-blogs-02.jpg","type":"image\/jpeg"}],"author":"Damien Goubeau","twitter_card":"summary_large_image","twitter_creator":"@MercatorOcean","twitter_site":"@MercatorOcean","twitter_misc":{"\u00c9crit par":"Damien Goubeau","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/#article","isPartOf":{"@id":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/"},"author":{"name":"Damien Goubeau","@id":"https:\/\/www.mercator-ocean.eu\/fr\/#\/schema\/person\/8707759d6e2641e91ea76ae3fc537134"},"headline":"Le monde.fr &#8211; Du climat au Syst\u00e8me Terre : l\u2019\u00e9volution des mod\u00e8les globaux","datePublished":"2018-06-25T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/"},"wordCount":1976,"commentCount":0,"publisher":{"@id":"https:\/\/www.mercator-ocean.eu\/fr\/#organization"},"image":{"@id":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mercator-ocean.eu\/wp-content\/uploads\/2024\/03\/logo-M-blogs-02.jpg","articleSection":["On parle de nous"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/","url":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/","name":"Le monde.fr - Du climat au Syst\u00e8me Terre : l\u2019\u00e9volution des mod\u00e8les globaux - Mercator Ocean International","isPartOf":{"@id":"https:\/\/www.mercator-ocean.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/#primaryimage"},"image":{"@id":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mercator-ocean.eu\/wp-content\/uploads\/2024\/03\/logo-M-blogs-02.jpg","datePublished":"2018-06-25T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/#primaryimage","url":"https:\/\/www.mercator-ocean.eu\/wp-content\/uploads\/2024\/03\/logo-M-blogs-02.jpg","contentUrl":"https:\/\/www.mercator-ocean.eu\/wp-content\/uploads\/2024\/03\/logo-M-blogs-02.jpg","width":700,"height":247},{"@type":"BreadcrumbList","@id":"https:\/\/www.mercator-ocean.eu\/fr\/on-parle-de-nous\/monde-fr-climat-systeme-terre-levolution-modeles-globaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mercator-ocean.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Le monde.fr &#8211; Du climat au Syst\u00e8me Terre : l\u2019\u00e9volution des mod\u00e8les globaux"}]},{"@type":"WebSite","@id":"https:\/\/www.mercator-ocean.eu\/fr\/#website","url":"https:\/\/www.mercator-ocean.eu\/fr\/","name":"Mercator Ocean International","description":"","publisher":{"@id":"https:\/\/www.mercator-ocean.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mercator-ocean.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.mercator-ocean.eu\/fr\/#organization","name":"Mercator Ocean International","url":"https:\/\/www.mercator-ocean.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mercator-ocean.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.mercator-ocean.eu\/wp-content\/uploads\/2024\/12\/logo-mercator.png","contentUrl":"https:\/\/www.mercator-ocean.eu\/wp-content\/uploads\/2024\/12\/logo-mercator.png","width":541,"height":547,"caption":"Mercator Ocean International"},"image":{"@id":"https:\/\/www.mercator-ocean.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MercatorOcean","https:\/\/x.com\/MercatorOcean","https:\/\/www.instagram.com\/mercator_ocean\/","https:\/\/www.linkedin.com\/company\/mercator-ocean\/","https:\/\/www.youtube.com\/user\/MERCATOROCEAN"]},{"@type":"Person","@id":"https:\/\/www.mercator-ocean.eu\/fr\/#\/schema\/person\/8707759d6e2641e91ea76ae3fc537134","name":"Damien Goubeau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/62d2ec81cbbe6e9a2a721e1d515895cfdffad7498f8f55b118245bbb7dc6b982?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/62d2ec81cbbe6e9a2a721e1d515895cfdffad7498f8f55b118245bbb7dc6b982?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62d2ec81cbbe6e9a2a721e1d515895cfdffad7498f8f55b118245bbb7dc6b982?s=96&d=mm&r=g","caption":"Damien Goubeau"},"url":"https:\/\/www.mercator-ocean.eu\/fr\/author\/damien-goubeau\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mercator-ocean.eu\/fr\/wp-json\/wp\/v2\/posts\/10247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mercator-ocean.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mercator-ocean.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mercator-ocean.eu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mercator-ocean.eu\/fr\/wp-json\/wp\/v2\/comments?post=10247"}],"version-history":[{"count":0,"href":"https:\/\/www.mercator-ocean.eu\/fr\/wp-json\/wp\/v2\/posts\/10247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mercator-ocean.eu\/fr\/wp-json\/wp\/v2\/media\/6756"}],"wp:attachment":[{"href":"https:\/\/www.mercator-ocean.eu\/fr\/wp-json\/wp\/v2\/media?parent=10247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mercator-ocean.eu\/fr\/wp-json\/wp\/v2\/categories?post=10247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mercator-ocean.eu\/fr\/wp-json\/wp\/v2\/tags?post=10247"},{"taxonomy":"translation-status","embeddable":true,"href":"https:\/\/www.mercator-ocean.eu\/fr\/wp-json\/wp\/v2\/translation-status?post=10247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}